{"id":59241,"date":"2025-06-27T13:52:26","date_gmt":"2025-06-27T11:52:26","guid":{"rendered":"https:\/\/klankennest.be\/?post_type=kalender&#038;p=59241"},"modified":"2025-06-27T13:52:26","modified_gmt":"2025-06-27T11:52:26","slug":"babyconcerten-kong-20-06","status":"publish","type":"kalender","link":"https:\/\/klankennest.be\/fr\/kalender\/babyconcerten-kong-20-06\/","title":{"rendered":"Babyconcerten Kong 20\/06"},"template":"","class_list":["post-59241","kalender","type-kalender","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/klankennest.be\/fr\/wp-json\/wp\/v2\/kalender\/59241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/klankennest.be\/fr\/wp-json\/wp\/v2\/kalender"}],"about":[{"href":"https:\/\/klankennest.be\/fr\/wp-json\/wp\/v2\/types\/kalender"}],"wp:attachment":[{"href":"https:\/\/klankennest.be\/fr\/wp-json\/wp\/v2\/media?parent=59241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}